{"id":4987,"date":"2020-11-11T06:08:59","date_gmt":"2020-11-11T06:08:59","guid":{"rendered":"http:\/\/camposcorporacion.com\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/"},"modified":"2023-05-24T06:54:53","modified_gmt":"2023-05-24T06:54:53","slug":"averias-comunes-en-la-refrigeracion-de-centros-de-datos-i","status":"publish","type":"post","link":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/","title":{"rendered":"Aver\u00edas comunes en la refrigeraci\u00f3n de Centros de Datos (I)"},"content":{"rendered":"<h2><b>ANALIZAMOS LAS AVER\u00cdAS COMUNES EN M\u00c1QUINAS FRIGOR\u00cdFICAS DE EXPANSI\u00d3N DIRECTA EN CPDS<br \/>\n<\/b><\/h2>\n<h3><b>EN CONCRETO, EN ESTE ART\u00cdCULO, LOS PROBLEMAS POR BAJA PRESI\u00d3N EN CENTROS DE DATOS<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Actualmente, las <strong>m\u00e1quinas frigor\u00edficas de expansi\u00f3n directa son la soluci\u00f3n preferida por muchos operadores para <a href=\"https:\/\/clysema.com\/tendencias-climatizacion-centros-de-datos\/\">refrigerar sus centros de datos<\/a><\/strong>. El principio de funcionamiento de estas m\u00e1quinas est\u00e1 basado en un ciclo termodin\u00e1mico conocido como <a href=\"https:\/\/es.wikipedia.org\/wiki\/Ciclo_de_Carnot\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>ciclo inverso de Carnot<\/strong><\/a>. Este ciclo est\u00e1 compuesto principalmente por <strong>4 elementos<\/strong> mec\u00e1nicos: un evaporador, un compresor, un condensador y una v\u00e1lvula de expansi\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El proceso consiste en forzar la circulaci\u00f3n c\u00edclica de un refrigerante a trav\u00e9s de estos 4 elementos de manera que el refrigerante absorba en el evaporador (tambi\u00e9n conocido como unidad interior) el calor de la sala que se quiere refrigerar, y lo libere al ambiente en el condensador o unidad exterior. De esta forma se generan <strong>2 zonas diferenciadas por sus presiones: la zona de baja presi\u00f3n<\/strong>, localizada en el evaporador, y la <strong>zona de alta presi\u00f3n<\/strong> en el condensador.<\/span><\/p>\n<h3><strong><a class=\"dt-single-image\" href=\"https:\/\/clysema.com\/wp-content\/uploads\/2020\/11\/clysema-averias-maquinas-refrigeracion-1.jpg\" data-dt-img-description=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1773 size-full\" src=\"http:\/\/camposcorporacion.com\/wp-content\/uploads\/2020\/11\/clysema-averias-maquinas-refrigeracion-1.jpg\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" alt=\"clysema-aver\u00edas-refrigeraci\u00f3n-centro-de-datos\" width=\"453\" height=\"241\" \/><\/a><\/strong><\/h3>\n<h3><strong>PROBLEMAS COMUNES EN EL FUNCIONAMIENTO DE ESTOS EQUIPOS<\/strong><\/h3>\n<p><b>A pesar de la aparente simplicidad de este ciclo termodin\u00e1mico<\/b><span style=\"font-weight: 400;\">, <\/span><b>el funcionamiento de las m\u00e1quinas se complica debido a que las condiciones de funcionamiento no son siempre las mismas<\/b><span style=\"font-weight: 400;\">, ya que en un mismo emplazamiento no siempre se cuenta con las mismas condiciones meteorol\u00f3gicas y adem\u00e1s, la temperatura de la sala fluct\u00faa en funci\u00f3n de la carga t\u00e9rmica de los equipos inform\u00e1ticos, lo que provoca que los par\u00e1metros de funcionamiento de la m\u00e1quina var\u00eden. Este motivo es el que hace que las <\/span><b>m\u00e1quinas sean sistemas complejos en los que la electr\u00f3nica juega un papel fundamenta<\/b><span style=\"font-weight: 400;\">l en la regulaci\u00f3n del funcionamiento de los elementos mec\u00e1nicos para asegurar que los par\u00e1metros termodin\u00e1micos del refrigerante est\u00e9n siempre dentro de los rangos correctos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta <\/span><b>complejidad deriva en primer lugar en numerosos focos de posibles desgastes y peque\u00f1as aver\u00edas<\/b><span style=\"font-weight: 400;\"> (obstrucciones del circuito, cierres deficientes en v\u00e1lvulas de regulaci\u00f3n de caudal\u2026) que tienen como <\/span><b>consecuencia directa la disminuci\u00f3n del rendimiento de la m\u00e1quina y por tanto, el aumento de consumo energ\u00e9tico<\/b><span style=\"font-weight: 400;\">, y en segundo lugar, en roturas y aver\u00edas graves que dejar\u00edan sin servicio a la sala. <\/span><b>El mantenimiento preventivo peri\u00f3dico de la m\u00e1quina y la comprobaci\u00f3n de los par\u00e1metros de funcionamiento son fundamentales<\/b><span style=\"font-weight: 400;\"> para alargar la vida de la misma y <a href=\"https:\/\/clysema.com\/calidad-red-data-centers\/\">abordar las deficiencias<\/a> antes de que la m\u00e1quina quede completamente fuera de servicio y sea necesario realizar un mantenimiento correctivo.<\/span><\/p>\n<h3><a href=\"https:\/\/camposcorporacion.com\/contacto\/?utm_source=blog&amp;utm_medium=post\" data-wplink-edit=\"true\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-16460 size-full\" src=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2015\/10\/CTA-campos-2-1.jpg\" alt=\"\" width=\"961\" height=\"251\" srcset=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2015\/10\/CTA-campos-2-1.jpg 961w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2015\/10\/CTA-campos-2-1-300x78.jpg 300w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2015\/10\/CTA-campos-2-1-768x201.jpg 768w\" sizes=\"auto, (max-width: 961px) 100vw, 961px\" \/><\/span><\/a><\/h3>\n<h3><b>QU\u00c9 DEBEMOS CONOCER PARA LOCALIZAR CORRECTAMENTE LAS AVER\u00cdAS<\/b><\/h3>\n<ul>\n<li><span style=\"font-weight: 400;\">Tipo de refrigerante y sus par\u00e1metros de funcionamiento (temperaturas y presiones en funci\u00f3n de las condiciones de la sala y del ambiente).<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Condiciones externas (temperatura y humedad de la sala y del ambiente exterior)<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Ciclo de trabajo y componentes de la m\u00e1quina<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Elementos de la instalaci\u00f3n y comportamiento de la sala<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Los <strong>puntos m\u00e1s localizados<\/strong> del circuito donde se suelen producir aver\u00edas son:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Compresores<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Sistema de expansi\u00f3n<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Zona de alta presi\u00f3n<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Zona de baja presi\u00f3n<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Cabe destacar que, aunque las aver\u00edas se produzcan en puntos localizados, se traducen en anomal\u00edas generalizadas en toda la instalaci\u00f3n debido a la relaci\u00f3n c\u00edclica de todos los componentes, por lo que se podr\u00e1n detectar s\u00edntomas en otros puntos.<\/span><\/p>\n<h3><b>PRINCIPALES PROBLEMAS POR BAJA PRESI\u00d3N<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">En este art\u00edculo, y debido a que son anomal\u00edas bastante frecuentes, se van a abordar los problemas debidos a alarmas en la zona de baja presi\u00f3n de las m\u00e1quinas.\u00a0<\/span><span style=\"font-weight: 400;\">Las causas m\u00e1s repetidas son las siguientes:<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">Falta de refrigerante<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Falta de caudal de aire en el evaporador<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Aver\u00eda en la v\u00e1lvula de expansi\u00f3n<\/span><\/li>\n<\/ol>\n<h4><b>1. FALTA DE REFRIGERANTE\u00a0\u00a0<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">La falta de refrigerante en un circuito frigor\u00edfico puede estar motivada por:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Falta de carga inicial durante la puesta en marcha de la m\u00e1quina<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Fuga en la instalaci\u00f3n<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Esto hace que:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Puede saltar el presostato de m\u00ednima presi\u00f3n.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">El consumo el\u00e9ctrico del compresor es mayor debido a que el salto de presiones entre la zona de baja presi\u00f3n y la de alta es mayor.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">El refrigerante no se condensa completamente en el condensador, por lo que la v\u00e1lvula de expansi\u00f3n recibe una mezcla de l\u00edquido y gas, lo que puede provocar ruidos y har\u00e1 que sufra mayor desgaste.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Debido a que en la v\u00e1lvula de expansi\u00f3n se produce menos caudal de l\u00edquido que el de dise\u00f1o, el intercambio de calor en el evaporador es deficiente y por tanto, la eficiencia de la m\u00e1quina disminuye.<\/span><\/li>\n<\/ul>\n<h4><b>2. FALTA DE CAUDAL DE AIRE EN EL EVAPORADOR<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">La falta de caudal en el evaporador puede estar provocada por cualquier causa que aumente la p\u00e9rdida de carga en la conducci\u00f3n del aire por encima de la capacidad de los ventiladores de la m\u00e1quina:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Filtros sucios<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Cualquier obst\u00e1culo en la instalaci\u00f3n: deflectores, compuertas cerradas, elementos de otras instalaciones\u2026<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Esta falta de caudal provoca una deficiencia en el intercambio de calor en el evaporador, por lo que el caudal de refrigerante no se evapora completamente a su paso, y como consecuencia, llega una mezcla de l\u00edquido y vapor a la aspiraci\u00f3n del compresor, lo que puede causar su rotura. Como el caudal de vapor es menor que el de dise\u00f1o, la compresi\u00f3n tambi\u00e9n es deficiente y la presi\u00f3n y temperatura en el condensador disminuyen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como consecuencia, la temperatura del refrigerante va disminuyendo en cada ciclo, provocando la formaci\u00f3n de hielo en la bater\u00eda del evaporador, perjudicando a\u00fan m\u00e1s la transferencia de calor entre el aire y el refrigerante, y disminuyendo la presi\u00f3n y temperatura en este elemento del ciclo.<\/span><\/p>\n<h4><b>3. AVER\u00cdA EN LA V\u00c1LVULA DE EXPANSI\u00d3N<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">El funcionamiento de la v\u00e1lvula de expansi\u00f3n consiste en estrangular m\u00e1s o menos el caudal de refrigerante en funci\u00f3n de la informaci\u00f3n recibida por el bulbo que lleva asociado. Este bulbo se instala a la salida del evaporador y mide la temperatura de recalentamiento del refrigerante. Este recalentamiento se suele establecer entre 5 y 8\u00baC, por lo que en funci\u00f3n de la temperatura medida por el bulbo, la v\u00e1lvula de expansi\u00f3n se abre m\u00e1s o menos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando existen problemas por baja presi\u00f3n puede ser principalmente por:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Obstrucci\u00f3n de la v\u00e1lvula de expansi\u00f3n<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Posici\u00f3n inadecuada del bulbo<\/span><\/li>\n<li><span style=\"font-weight: 400;\">El bulbo no tiene un buen contacto con la tuber\u00eda de aspiraci\u00f3n<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Desgaste de la v\u00e1lvula de expansi\u00f3n<\/span><\/li>\n<\/ul>\n<h3><\/h3>\n<h3><\/h3>\n<h2><b>CONCLUSI\u00d3N PARA LAS AVER\u00cdAS COMUNES EN LA REFRIGERACI\u00d3N DE CENTROS DE PROCESO DE DATOS<br \/>\n<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Para diagnosticar cualquier tipo de aver\u00eda en la instalaci\u00f3n, es imprescindible <\/span><b>prestar atenci\u00f3n a cualquier s\u00edntoma o anomal\u00eda<\/b><span style=\"font-weight: 400;\"> respecto a las condiciones de funcionamiento habituales. Para ello, es necesario conocer bien la instalaci\u00f3n y realizar<\/span><b> revisiones frecuentes<\/b><span style=\"font-weight: 400;\"> de todas sus partes, as\u00ed como llevar a cabo un <\/span><b>seguimiento y dejar constancia de los par\u00e1metros m\u00e1s importantes<\/b><span style=\"font-weight: 400;\"> (presiones y temperaturas del ciclo, cargas de gas, niveles de aceite, saturaci\u00f3n de los filtros\u2026). Estos par\u00e1metros permitir\u00e1n<\/span><b> localizar a tiempo cualquier defecto<\/b><span style=\"font-weight: 400;\"> y su correcci\u00f3n precoz garantizando as\u00ed el buen funcionamiento de la instalaci\u00f3n frigor\u00edfica y, en consecuencia, del centro de datos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estos art\u00edculos pueden ser muy \u00fatiles para el correcto <strong>mantenimiento de instalaciones de climatizaci\u00f3n<\/strong> en centros de datos o en el sector industrial o comercial. Se trata del conocimiento adquirido en base a la experiencia de <a href=\"http:\/\/www.clysema.com\" target=\"_blank\" rel=\"noopener noreferrer\">Clysema<\/a> a lo largo de estos 30 a\u00f1os como <a href=\"https:\/\/clysema.com\/mantenimiento\/\">mantenedores de este tipo de instalaciones<\/a> y <a href=\"https:\/\/clysema.com\/otras-soluciones\/servicios-energeticos\/\">empresa de servicios energ\u00e9ticos<\/a>.<\/span><\/p>\n<p><em>Por Beatriz Garc\u00eda Bodas<\/em><\/p>\n<p><em>Jefe de Proyecto en Clysema<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANALIZAMOS LAS AVER\u00cdAS COMUNES EN M\u00c1QUINAS FRIGOR\u00cdFICAS DE EXPANSI\u00d3N DIRECTA EN CPDS EN CONCRETO, EN ESTE ART\u00cdCULO, LOS PROBLEMAS POR [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5144,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89,88],"tags":[],"class_list":["post-4987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-climatizacion","category-energia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aver\u00edas comunes en la refrigeraci\u00f3n de Centros de Datos (I) - Campos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aver\u00edas comunes en la refrigeraci\u00f3n de Centros de Datos (I) - Campos\" \/>\n<meta property=\"og:description\" content=\"ANALIZAMOS LAS AVER\u00cdAS COMUNES EN M\u00c1QUINAS FRIGOR\u00cdFICAS DE EXPANSI\u00d3N DIRECTA EN CPDS EN CONCRETO, EN ESTE ART\u00cdCULO, LOS PROBLEMAS POR [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/\" \/>\n<meta property=\"og:site_name\" content=\"Campos\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-11T06:08:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-24T06:54:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2020\/11\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2167\" \/>\n\t<meta property=\"og:image:height\" content=\"1133\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\\\/\"},\"author\":{\"name\":\"Campos\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#\\\/schema\\\/person\\\/28c4749bffada975dd2d764fd4efd894\"},\"headline\":\"Aver\u00edas comunes en la refrigeraci\u00f3n de Centros de Datos (I)\",\"datePublished\":\"2020-11-11T06:08:59+00:00\",\"dateModified\":\"2023-05-24T06:54:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\\\/\"},\"wordCount\":1352,\"publisher\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i.jpg\",\"articleSection\":[\"Climatizaci\u00f3n\",\"Energ\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\\\/\",\"url\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\\\/\",\"name\":\"Aver\u00edas comunes en la refrigeraci\u00f3n de Centros de Datos (I) - Campos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i.jpg\",\"datePublished\":\"2020-11-11T06:08:59+00:00\",\"dateModified\":\"2023-05-24T06:54:53+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\\\/#primaryimage\",\"url\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i.jpg\",\"contentUrl\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i.jpg\",\"width\":2167,\"height\":1133},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/\",\"name\":\"Campos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#organization\",\"name\":\"Campos Corporaci\u00f3n\",\"alternateName\":\"Campos\",\"url\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/campos-yoast.png\",\"contentUrl\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/campos-yoast.png\",\"width\":696,\"height\":696,\"caption\":\"Campos Corporaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#\\\/schema\\\/person\\\/28c4749bffada975dd2d764fd4efd894\",\"name\":\"Campos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g\",\"caption\":\"Campos\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aver\u00edas comunes en la refrigeraci\u00f3n de Centros de Datos (I) - Campos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/","og_locale":"en_US","og_type":"article","og_title":"Aver\u00edas comunes en la refrigeraci\u00f3n de Centros de Datos (I) - Campos","og_description":"ANALIZAMOS LAS AVER\u00cdAS COMUNES EN M\u00c1QUINAS FRIGOR\u00cdFICAS DE EXPANSI\u00d3N DIRECTA EN CPDS EN CONCRETO, EN ESTE ART\u00cdCULO, LOS PROBLEMAS POR [&hellip;]","og_url":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/","og_site_name":"Campos","article_published_time":"2020-11-11T06:08:59+00:00","article_modified_time":"2023-05-24T06:54:53+00:00","og_image":[{"width":2167,"height":1133,"url":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2020\/11\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i.jpg","type":"image\/jpeg"}],"author":"Campos","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Campos","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/#article","isPartOf":{"@id":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/"},"author":{"name":"Campos","@id":"https:\/\/camposcorporacion.com\/en\/#\/schema\/person\/28c4749bffada975dd2d764fd4efd894"},"headline":"Aver\u00edas comunes en la refrigeraci\u00f3n de Centros de Datos (I)","datePublished":"2020-11-11T06:08:59+00:00","dateModified":"2023-05-24T06:54:53+00:00","mainEntityOfPage":{"@id":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/"},"wordCount":1352,"publisher":{"@id":"https:\/\/camposcorporacion.com\/en\/#organization"},"image":{"@id":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/#primaryimage"},"thumbnailUrl":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2020\/11\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i.jpg","articleSection":["Climatizaci\u00f3n","Energ\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/","url":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/","name":"Aver\u00edas comunes en la refrigeraci\u00f3n de Centros de Datos (I) - Campos","isPartOf":{"@id":"https:\/\/camposcorporacion.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/#primaryimage"},"image":{"@id":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/#primaryimage"},"thumbnailUrl":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2020\/11\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i.jpg","datePublished":"2020-11-11T06:08:59+00:00","dateModified":"2023-05-24T06:54:53+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/camposcorporacion.com\/en\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i\/#primaryimage","url":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2020\/11\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i.jpg","contentUrl":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2020\/11\/averias-comunes-en-la-refrigeracion-de-centros-de-datos-i.jpg","width":2167,"height":1133},{"@type":"WebSite","@id":"https:\/\/camposcorporacion.com\/en\/#website","url":"https:\/\/camposcorporacion.com\/en\/","name":"Campos","description":"","publisher":{"@id":"https:\/\/camposcorporacion.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/camposcorporacion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/camposcorporacion.com\/en\/#organization","name":"Campos Corporaci\u00f3n","alternateName":"Campos","url":"https:\/\/camposcorporacion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/camposcorporacion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2026\/03\/campos-yoast.png","contentUrl":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2026\/03\/campos-yoast.png","width":696,"height":696,"caption":"Campos Corporaci\u00f3n"},"image":{"@id":"https:\/\/camposcorporacion.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/camposcorporacion.com\/en\/#\/schema\/person\/28c4749bffada975dd2d764fd4efd894","name":"Campos","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g","caption":"Campos"}}]}},"_links":{"self":[{"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/posts\/4987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/comments?post=4987"}],"version-history":[{"count":0,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/posts\/4987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/media\/5144"}],"wp:attachment":[{"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/media?parent=4987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/categories?post=4987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/tags?post=4987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}