{"id":21107,"date":"2025-08-20T10:53:47","date_gmt":"2025-08-20T08:53:47","guid":{"rendered":"https:\/\/camposcorporacion.com\/?p=21107"},"modified":"2025-08-20T14:03:35","modified_gmt":"2025-08-20T12:03:35","slug":"deporte-regional-lagunas-series-2025","status":"publish","type":"post","link":"https:\/\/camposcorporacion.com\/en\/deporte-regional-lagunas-series-2025\/","title":{"rendered":"Campos renueva su compromiso con el deporte regional apoyando el circuito Lagunas Series 2025"},"content":{"rendered":"\n<p>En Campos seguimos impulsando el deporte regional a trav\u00e9s de nuestra colaboraci\u00f3n con el circuito de duatl\u00f3n y triatl\u00f3n <strong>Lagunas Series<\/strong>. Para 2025, renovamos nuestro compromiso con esta prestigiosa competici\u00f3n organizada por el <strong>Club Triatl\u00e9tico Tomelloso<\/strong>, consolidando nuestra apuesta por fomentar el deporte base y las actividades saludables en Castilla-La Mancha.<\/p>\n\n\n\n<p>La edici\u00f3n 2025 del circuito <strong>Lagunas Series <\/strong>incluye siete pruebas deportivas que se han celebrado en entornos emblem\u00e1ticos como <strong>Tomelloso<\/strong>, <strong>Ruidera<\/strong> y <strong>Ossa de Montiel<\/strong>, varias de ellas puntuables para el Campeonato de Castilla-La Mancha en sus diferentes modalidades.<\/p>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/6-1024x683.jpg\" alt=\"\" class=\"wp-image-21116\" style=\"aspect-ratio:16\/9;object-fit:cover\" srcset=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/6-1024x683.jpg 1024w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/6-300x200.jpg 300w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/6-768x512.jpg 768w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/6-1536x1024.jpg 1536w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/6-2048x1365.jpg 2048w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/6-500x333.jpg 500w\" \/><figcaption class=\"wp-element-caption\">Carreras Trilagunas 2025<\/figcaption><\/figure>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/MG_8985-1024x683.jpg\" alt=\"\" class=\"wp-image-21112\" style=\"aspect-ratio:16\/9;object-fit:cover\" srcset=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/MG_8985-1024x683.jpg 1024w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/MG_8985-300x200.jpg 300w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/MG_8985-768x512.jpg 768w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/MG_8985-1536x1024.jpg 1536w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/MG_8985-2048x1366.jpg 2048w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/MG_8985-500x333.jpg 500w\" \/><figcaption class=\"wp-element-caption\">Carreras Trilagunas 2025<\/figcaption><\/figure>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/4-1024x683.jpg\" alt=\"\" class=\"wp-image-21114\" style=\"aspect-ratio:16\/9;object-fit:cover\" srcset=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/4-1024x683.jpg 1024w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/4-300x200.jpg 300w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/4-768x512.jpg 768w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/4-1536x1024.jpg 1536w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/4-2048x1365.jpg 2048w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/4-500x333.jpg 500w\" \/><figcaption class=\"wp-element-caption\">Carreras Trilagunas 2025<\/figcaption><\/figure>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong><strong>Calendario de pruebas 2025<\/strong><\/strong><\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>26 de enero<\/strong> \u2013 Ducross \u201cConrado Garc\u00eda\u201d en Ossa de Montiel.<\/li>\n\n\n\n<li><strong>16 de marzo<\/strong> \u2013 Duatl\u00f3n Ciudad de Tomelloso.<\/li>\n\n\n\n<li><strong>24 de mayo<\/strong> \u2013 Acuatl\u00f3n de Tomelloso.<\/li>\n\n\n\n<li><strong>25 de mayo<\/strong> \u2013 TriRuidera: Triatl\u00f3n ol\u00edmpico celebrado en la Laguna del Rey, en Ruidera.<\/li>\n\n\n\n<li><strong>14 de junio<\/strong> \u2013 Campeonato Regional de Triatl\u00f3n de Deporte Escolar.<\/li>\n\n\n\n<li><strong>15 de junio<\/strong> \u2013 TriTomelloso: Triatl\u00f3n sprint, Campeonato de Castilla-La Mancha.<\/li>\n\n\n\n<li><strong>23 de noviembre<\/strong> \u2013 Ducross \u201cMiguel \u00c1ngel Moreno\u201d en Tomelloso.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/9-1024x683.jpg\" alt=\"\" class=\"wp-image-21126\" style=\"aspect-ratio:16\/9;object-fit:cover\" srcset=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/9-1024x683.jpg 1024w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/9-300x200.jpg 300w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/9-768x512.jpg 768w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/9-1536x1024.jpg 1536w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/9-2048x1365.jpg 2048w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/9-500x333.jpg 500w\" \/><figcaption class=\"wp-element-caption\">Carreras Trilagunas 2025<\/figcaption><\/figure>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong><strong><strong>Juntos por el deporte con el Club Triatl\u00e9tico Tomelloso<\/strong><\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p>En Campos, nuestro patrocinio no solo se limita a estas pruebas deportivas, sino que tambi\u00e9n respalda la actividad diaria del <strong>Club Triatl\u00e9tico Tomelloso<\/strong>. El club juega un papel activo en la organizaci\u00f3n de eventos deportivos clave para la comunidad, como la <strong>Carrera contra el C\u00e1ncer<\/strong>, el <strong>Campeonato de Castilla-La Mancha de ciclismo escolar<\/strong>, el <strong>10K Ciudad de Tomelloso<\/strong> y el <strong>Open BTT<\/strong>.<\/p>\n\n\n\n<p>Adem\u00e1s, el club desarrolla una importante<strong> labor formativa<\/strong> para deportistas de todas las edades, con jornadas de entrenamiento y tecnificaci\u00f3n orientadas a mejorar las habilidades t\u00e9cnicas y f\u00edsicas de los participantes, fomentando as\u00ed el deporte base y la promoci\u00f3n de<strong> h\u00e1bitos de vida saludables<\/strong>.<\/p>\n\n\n\n<p>La temporada 2025 del circuito <strong>Lagunas Series<\/strong> concluir\u00e1 pr\u00f3ximamente en Tomelloso con la \u00faltima prueba del calendario, cerrando un a\u00f1o m\u00e1s de compromiso y apoyo al deporte regional.<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/3-1024x683.jpg\" alt=\"\" class=\"wp-image-21120\" style=\"aspect-ratio:16\/9;object-fit:cover\" srcset=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/3-1024x683.jpg 1024w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/3-300x200.jpg 300w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/3-768x512.jpg 768w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/3-1536x1024.jpg 1536w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/3-2048x1365.jpg 2048w, https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/3-500x333.jpg 500w\" \/><figcaption class=\"wp-element-caption\">Carreras Trilagunas 2025<\/figcaption><\/figure>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><strong><strong><strong><strong>M\u00e1s informaci\u00f3n y enlaces de inter\u00e9s<\/strong><\/strong><\/strong><\/strong><\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-left\">\ud83d\udc49 Para m\u00e1s informaci\u00f3n sobre todas las competiciones, las actividades del <strong>Club Triatl\u00e9tico Tomelloso<\/strong> y los detalles oficiales del circuito, puedes visitar la p\u00e1gina de<a href=\"https:\/\/rutasdelvinotomell.wixsite.com\/rutasdelvino\" target=\"_blank\" rel=\"noreferrer noopener\"> Rutas del Vino Tomelloso<\/a>, el sitio oficial de <a href=\"https:\/\/triruidera.wixsite.com\/triruidera\" target=\"_blank\" rel=\"noreferrer noopener\">TriRuidera<\/a>, la web del <a href=\"https:\/\/trilagunas.wixsite.com\/conradogarcia\" target=\"_blank\" rel=\"noreferrer noopener\">Ducross Conrado Garc\u00eda<\/a> y la p\u00e1gina principal del <a href=\"https:\/\/somostriatletico.wixsite.com\/triatletico\/inicio\" target=\"_blank\" rel=\"noreferrer noopener\">Club Triatl\u00e9tico Tomelloso<\/a>.<br><\/p>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:45px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Campos seguimos impulsando el deporte regional a trav\u00e9s de nuestra colaboraci\u00f3n con el circuito de duatl\u00f3n y triatl\u00f3n Lagunas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"class_list":["post-21107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-corporativas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campos renueva su compromiso con el deporte regional apoyando el circuito Lagunas Series 2025 - Campos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campos renueva su compromiso con el deporte regional apoyando el circuito Lagunas Series 2025 - Campos\" \/>\n<meta property=\"og:description\" content=\"En Campos seguimos impulsando el deporte regional a trav\u00e9s de nuestra colaboraci\u00f3n con el circuito de duatl\u00f3n y triatl\u00f3n Lagunas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Campos\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-20T08:53:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-20T12:03:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/Portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/deporte-regional-lagunas-series-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/deporte-regional-lagunas-series-2025\\\/\"},\"author\":{\"name\":\"Campos\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#\\\/schema\\\/person\\\/28c4749bffada975dd2d764fd4efd894\"},\"headline\":\"Campos renueva su compromiso con el deporte regional apoyando el circuito Lagunas Series 2025\",\"datePublished\":\"2025-08-20T08:53:47+00:00\",\"dateModified\":\"2025-08-20T12:03:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/deporte-regional-lagunas-series-2025\\\/\"},\"wordCount\":407,\"publisher\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/deporte-regional-lagunas-series-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Portada.jpg\",\"articleSection\":[\"Noticias corporativas\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/deporte-regional-lagunas-series-2025\\\/\",\"url\":\"https:\\\/\\\/camposcorporacion.com\\\/deporte-regional-lagunas-series-2025\\\/\",\"name\":\"Campos renueva su compromiso con el deporte regional apoyando el circuito Lagunas Series 2025 - Campos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/deporte-regional-lagunas-series-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/deporte-regional-lagunas-series-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Portada.jpg\",\"datePublished\":\"2025-08-20T08:53:47+00:00\",\"dateModified\":\"2025-08-20T12:03:35+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/camposcorporacion.com\\\/deporte-regional-lagunas-series-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/deporte-regional-lagunas-series-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Portada.jpg\",\"contentUrl\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Portada.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/\",\"name\":\"Campos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#organization\",\"name\":\"Campos Corporaci\u00f3n\",\"alternateName\":\"Campos\",\"url\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/campos-yoast.png\",\"contentUrl\":\"https:\\\/\\\/camposcorporacion.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/campos-yoast.png\",\"width\":696,\"height\":696,\"caption\":\"Campos Corporaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/camposcorporacion.com\\\/en\\\/#\\\/schema\\\/person\\\/28c4749bffada975dd2d764fd4efd894\",\"name\":\"Campos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g\",\"caption\":\"Campos\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campos renueva su compromiso con el deporte regional apoyando el circuito Lagunas Series 2025 - Campos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/","og_locale":"en_US","og_type":"article","og_title":"Campos renueva su compromiso con el deporte regional apoyando el circuito Lagunas Series 2025 - Campos","og_description":"En Campos seguimos impulsando el deporte regional a trav\u00e9s de nuestra colaboraci\u00f3n con el circuito de duatl\u00f3n y triatl\u00f3n Lagunas [&hellip;]","og_url":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/","og_site_name":"Campos","article_published_time":"2025-08-20T08:53:47+00:00","article_modified_time":"2025-08-20T12:03:35+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/Portada.jpg","type":"image\/jpeg"}],"author":"Campos","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Campos","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/#article","isPartOf":{"@id":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/"},"author":{"name":"Campos","@id":"https:\/\/camposcorporacion.com\/en\/#\/schema\/person\/28c4749bffada975dd2d764fd4efd894"},"headline":"Campos renueva su compromiso con el deporte regional apoyando el circuito Lagunas Series 2025","datePublished":"2025-08-20T08:53:47+00:00","dateModified":"2025-08-20T12:03:35+00:00","mainEntityOfPage":{"@id":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/"},"wordCount":407,"publisher":{"@id":"https:\/\/camposcorporacion.com\/en\/#organization"},"image":{"@id":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/Portada.jpg","articleSection":["Noticias corporativas"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/","url":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/","name":"Campos renueva su compromiso con el deporte regional apoyando el circuito Lagunas Series 2025 - Campos","isPartOf":{"@id":"https:\/\/camposcorporacion.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/#primaryimage"},"image":{"@id":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/Portada.jpg","datePublished":"2025-08-20T08:53:47+00:00","dateModified":"2025-08-20T12:03:35+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/camposcorporacion.com\/deporte-regional-lagunas-series-2025\/#primaryimage","url":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/Portada.jpg","contentUrl":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2025\/08\/Portada.jpg","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/camposcorporacion.com\/en\/#website","url":"https:\/\/camposcorporacion.com\/en\/","name":"Campos","description":"","publisher":{"@id":"https:\/\/camposcorporacion.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/camposcorporacion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/camposcorporacion.com\/en\/#organization","name":"Campos Corporaci\u00f3n","alternateName":"Campos","url":"https:\/\/camposcorporacion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/camposcorporacion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2026\/03\/campos-yoast.png","contentUrl":"https:\/\/camposcorporacion.com\/wp-content\/uploads\/2026\/03\/campos-yoast.png","width":696,"height":696,"caption":"Campos Corporaci\u00f3n"},"image":{"@id":"https:\/\/camposcorporacion.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/camposcorporacion.com\/en\/#\/schema\/person\/28c4749bffada975dd2d764fd4efd894","name":"Campos","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/348e3148e60a9d417f4c7f711aaf87be299fbcf0e73ff7db0a825e5c3ff7d166?s=96&d=mm&r=g","caption":"Campos"}}]}},"_links":{"self":[{"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/posts\/21107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/comments?post=21107"}],"version-history":[{"count":0,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/posts\/21107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/media\/21108"}],"wp:attachment":[{"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/media?parent=21107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/categories?post=21107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposcorporacion.com\/en\/wp-json\/wp\/v2\/tags?post=21107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}